{"id":5026,"date":"2020-02-22T16:47:48","date_gmt":"2020-02-22T15:47:48","guid":{"rendered":"http:\/\/www.tempsetor.be\/galerie\/?post_type=product&#038;p=5026"},"modified":"2020-02-22T17:03:47","modified_gmt":"2020-02-22T16:03:47","slug":"bague-flanders-065ct-187","status":"publish","type":"product","link":"https:\/\/tempsetor.be\/galerie\/produit\/bague-flanders-065ct-187\/","title":{"rendered":"Bague Flanders or blanc &#8211; 0,65ct &#8211; RBG187"},"content":{"rendered":"<p>Le brillant Flanders fut d\u00e9velopp\u00e9 en 1983. Il a \u00e9t\u00e9 taill\u00e9 et perfectionn\u00e9 \u00e0 partir de 1987 dans une petite taillerie pr\u00e8s d\u2019Anvers. C\u2019est l\u00e0 que ce diamant exceptionnel re\u00e7ut son<br \/>\nnom d\u00e9finitif.<\/p>\n<p>Anvers est consid\u00e9r\u00e9e comme la capitale mondiale du diamant. Plus de 50% de la production mondiale de diamants bruts et taill\u00e9s transite par cette ville.<\/p>\n","protected":false},"excerpt":{"rendered":"<div id=\"oorsprong_tekst\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3622\" src=\"https:\/\/tempsetor.be\/galerie\/wp-content\/uploads\/2018\/02\/flanders-logo-150px.jpg\" alt=\"\" width=\"150\" height=\"53\" srcset=\"https:\/\/tempsetor.be\/galerie\/wp-content\/uploads\/2018\/02\/flanders-logo-150px.jpg 150w, https:\/\/tempsetor.be\/galerie\/wp-content\/uploads\/2018\/02\/flanders-logo-150px-50x18.jpg 50w\" sizes=\"auto, (max-width:767px) 150px, 150px\" \/><\/p>\n<p>Bijoutiers &#8211; artisans depuis plus de 20 ans, la bijouterie <strong>Temps &amp; OR <\/strong>vous apporte la s\u00e9curit\u00e9 d&#8217;une s\u00e9lection de lignes de bijoux en OR 18 karats soign\u00e9es et cr\u00e9es par des professionnels d&#8217;exp\u00e9rience. Ateliers de bijouterie sur place &#8211; Selon vos besoins, ces bijoux peuvent \u00eatre \u00e9galement r\u00e9serv\u00e9s \u00e0 la bijouterie. La mise \u00e0 mesure offerte ainsi qu&#8217;un emballage cadeau vous y seront propos\u00e9s.<\/p>\n<p>Faites vos demandes particuli\u00e8res ou passez votre commande via ce formulaire :<br \/>\n<p class=\"wpcf7-contact-form-not-found\"><strong>Error:<\/strong> Contact form not found.<\/p><\/p>\n<\/div>\n","protected":false},"featured_media":5027,"template":"","meta":{"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[30,529,27],"product_tag":[],"class_list":["post-5026","product","type-product","status-publish","has-post-thumbnail","product_cat-bagues-femmes","product_cat-flanders-bague","product_cat-dames","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/tempsetor.be\/galerie\/wp-json\/wp\/v2\/product\/5026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tempsetor.be\/galerie\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tempsetor.be\/galerie\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tempsetor.be\/galerie\/wp-json\/wp\/v2\/media\/5027"}],"wp:attachment":[{"href":"https:\/\/tempsetor.be\/galerie\/wp-json\/wp\/v2\/media?parent=5026"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tempsetor.be\/galerie\/wp-json\/wp\/v2\/product_brand?post=5026"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tempsetor.be\/galerie\/wp-json\/wp\/v2\/product_cat?post=5026"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tempsetor.be\/galerie\/wp-json\/wp\/v2\/product_tag?post=5026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}